{"id":1356,"date":"2024-01-20T14:32:24","date_gmt":"2024-01-20T13:32:24","guid":{"rendered":"https:\/\/www.systra.com\/denmark\/?page_id=1356"},"modified":"2026-02-27T10:34:15","modified_gmt":"2026-02-27T09:34:15","slug":"ledelse-i-danmark","status":"publish","type":"page","link":"https:\/\/www.systra.com\/denmark\/hvem-vi-er\/ledelse-i-danmark\/","title":{"rendered":"Ledelse i Danmark"},"content":{"rendered":"\n<h2 class=\"wp-block-heading alignfull has-pale-mauve-background-color has-background\" id=\"h-direktion\">DIREKTION<\/h2>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1705\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-scaled.png\" alt=\"\" class=\"wp-image-47741\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-scaled.png 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-300x200.png 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-1024x682.png 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-768x512.png 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-1536x1023.png 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-2048x1364.png 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-375x250.png 375w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-376x250.png 376w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-474x316.png 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-75x50.png 75w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-900x600.png 900w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-1700x1132.png 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-1352x901.png 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-800x533.png 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-180x120.png 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-153x102.png 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/08\/final-final-final-eva-ny-small-230x153.png 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-eva-rindom\">Eva rindom<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Administrerende direkt\u00f8r<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-4eeec98213b9900bd3366c2a16d0aa62\"><a href=\"mailto:erindom@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">ERINDOM@systra.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1705\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-scaled.jpg\" alt=\"\" class=\"wp-image-45661\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-300x200.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-1024x682.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-768x512.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-1536x1023.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-2048x1364.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-375x250.jpg 375w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-376x250.jpg 376w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-474x316.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-75x50.jpg 75w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-900x600.jpg 900w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-1700x1132.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-1352x900.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-800x533.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-180x120.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-153x102.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/kristian-2025-small-ny-230x153.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-kristian-quarder\">Kristian Quarder<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Finansdirekt\u00f8r<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-353931ed33d9005244db9cfd19733408\"><a href=\"mailto:KQUARDER@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">KQUARDER@systra.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1705\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-scaled.jpg\" alt=\"\" class=\"wp-image-45663\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-300x200.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-1024x682.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-768x512.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-1536x1023.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-2048x1364.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-375x250.jpg 375w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-376x250.jpg 376w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-474x316.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-75x50.jpg 75w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-900x600.jpg 900w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-1700x1132.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-1352x901.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-800x533.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-180x120.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-153x102.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/annelise-small-2025-ny-230x153.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-annelise-zidi\">Annelise zidi<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>HR-direkt\u00f8r<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-968e2014e60570fa877488d97e5f9a1d\"><a href=\"mailto:AZIDI@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">AZIDI@systra.com<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-scaled.jpg\" alt=\"\" class=\"wp-image-45664\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-300x200.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-1024x682.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-768x512.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-1536x1024.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-2048x1365.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-375x250.jpg 375w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-376x250.jpg 376w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-474x316.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-75x50.jpg 75w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-900x600.jpg 900w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-1700x1133.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-1352x901.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-800x533.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-180x120.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-153x102.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/eli-2025-small-230x153.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-eli-skop\">Eli SKop<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Direkt\u00f8r, Consultancy<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-45f401ee75e9bb18bd3c35d9ae5f87b3\"><a href=\"mailto:ESKOP@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">ESKOP@systra.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1705\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-scaled.jpg\" alt=\"\" class=\"wp-image-45665\" style=\"object-fit:contain;width:650px;height:433px\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-300x200.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-1024x682.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-768x512.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-1536x1023.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-2048x1364.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-375x250.jpg 375w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-376x250.jpg 376w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-474x316.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-75x50.jpg 75w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-900x600.jpg 900w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-1700x1132.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-1352x901.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-800x533.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-180x120.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-153x102.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/claus-2025-small-230x153.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-claus-madvig-petersen\">Claus Madvig Petersen<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-dirty-purple-color has-text-color has-link-color wp-elements-673aeca1dee89f74da50f87334366983\">Direkt\u00f8r, Civils<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-3903603d51616a56881ce5a838cb1519\"><a href=\"mailto:CPETERSEN@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">CPETERSEN@systra.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1705\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-scaled.jpg\" alt=\"\" class=\"wp-image-45666\" style=\"object-fit:contain;width:650px;height:433px\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-300x200.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-1024x682.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-768x512.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-1536x1023.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-2048x1364.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-375x250.jpg 375w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-376x250.jpg 376w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-474x316.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-75x50.jpg 75w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-900x600.jpg 900w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-1700x1133.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-1352x901.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-800x533.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-180x120.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-153x102.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/07\/thomas-2025-small-230x153.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-thomas-vesterholm\">Thomas Vesterholm<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Direkt\u00f8r, Rail<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-b1c9db545ee7146f797fd302685a4ad1\"><a href=\"tvesterholm@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">TVESTERHOLM@systra.com<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading alignfull has-pale-mauve-background-color has-background\" id=\"h-afdelingsledelse\">AFDELINGSLEDELSE<\/h2>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"96\" height=\"96\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/05\/person.png\" alt=\"\" class=\"wp-image-8084\" style=\"width:176px;height:auto\"\/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-julie-feddersen\">Julie Feddersen<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Gruppeleder<br>Spor og anl\u00e6g<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-4782e4ffd94bb784ff5f65805280ea59\"><a href=\"mailto:JJFEDDERSEN@systra.com\">JJFEDDERSEN@systra.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-scaled.jpg\" alt=\"\" class=\"wp-image-1975\" style=\"width:197px;height:auto\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-300x225.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-1024x768.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-768x576.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-1536x1152.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-2048x1536.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-474x355.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-1700x1275.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-1352x1014.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-800x600.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-180x135.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-153x115.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hart3114-1-230x172.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-johan-hartnack\">Johan Hartnack<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Afdelingschef<br>GIS &amp; digital<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-02bf3bc69e99a24b1aba40fc8d1fa2c0\"><a href=\"mailto:JHARTNACK@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">JHARTNACK@systra.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-scaled.jpg\" alt=\"\" class=\"wp-image-1967\" style=\"width:180px;height:auto\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-300x225.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-1024x768.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-768x576.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-1536x1152.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-2048x1536.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-474x356.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-1700x1275.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-1352x1014.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-800x600.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-180x135.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-153x115.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mikk0129-1-230x173.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-rune-mikkelsen\">Rune Mikkelsen<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Afdelingschef <br>Systems<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-1cdc6a7606f766a6c6a09319fcde0a2f\"><a href=\"mailto:RMIKKELSEN@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">RMIKKELSEN@systra.com<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"96\" height=\"96\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/05\/person.png\" alt=\"\" class=\"wp-image-8084\" style=\"width:176px;height:auto\"\/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-martin-vilhelmsen\">Martin Vilhelmsen<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Afdelingschef<br>Milj\u00f8, vand og areal<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-fc9f39bd6a4a831ff26471024cd2f637\"><a href=\"mailto:MVILHELMSEN@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">MVILHELMSEN@systra.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-scaled.jpg\" alt=\"\" class=\"wp-image-1968\" style=\"width:201px;height:auto\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-300x200.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-1024x683.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-768x512.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-1536x1024.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-2048x1365.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-375x250.jpg 375w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-376x250.jpg 376w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-474x316.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-75x50.jpg 75w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-900x600.jpg 900w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-1700x1133.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-1352x901.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-800x533.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-180x120.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-153x102.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/mani3316-1-230x153.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-rune-manique\">Rune manique<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Afdelingschef<br>Power Systems &amp; Overhead Line Equipment<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-96476602e9d45b8dc694f84deda6f4b2\"><a href=\"mailto:RMANIQUE@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">RMANIQUE@systra.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-scaled.jpg\" alt=\"\" class=\"wp-image-1969\" style=\"width:180px;height:auto\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-300x225.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-1024x768.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-768x576.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-1536x1152.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-2048x1536.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-474x355.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-1700x1275.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-1352x1014.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-800x600.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-180x135.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-153x115.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/vill6331-2-230x172.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-rasmus-svith\">Rasmus Svith<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Afdelingschef <br>Veje og planl\u00e6gning<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-da97f828d431c246157afb69b316080a\"><a href=\"mailto:RSVITH@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">RSVITH@systra.com<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1705\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-scaled.png\" alt=\"\" class=\"wp-image-51625\" style=\"width:186px;height:auto\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-scaled.png 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-300x200.png 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-1024x682.png 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-768x511.png 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-1536x1023.png 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-2048x1364.png 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-375x250.png 375w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-376x250.png 376w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-474x316.png 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-75x50.png 75w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-900x600.png 900w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-1700x1132.png 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-1352x900.png 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-800x533.png 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-180x120.png 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-153x102.png 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/09\/mbmandrup_ny-230x153.png 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-martin-mandrup\">Martin mandrup<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Afdelingschef<br>Projektledelse<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-c306b8c6e4d9de7d2cf3eb2f6d2288c6\"><a href=\"mailto:mbmandrup@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">MBMANDRUP@systra.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-scaled.jpg\" alt=\"\" class=\"wp-image-1971\" style=\"width:186px\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-300x200.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-1024x683.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-768x512.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-1536x1024.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-2048x1366.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-375x250.jpg 375w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-376x250.jpg 376w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-474x316.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-75x50.jpg 75w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-900x600.jpg 900w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-1700x1134.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-1352x902.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-800x533.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-180x120.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-153x102.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/norv6380-1-230x153.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-peter-norvin\">peter norvin<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Afdelingschef<br>Geoteknik og havne<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-67ed2a9ef48a2f594f794ff1b4903e9c\"><a href=\"mailto:PNORVIN@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">PNORVIN@systra.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" data-id=\"19626\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-scaled.jpg\" alt=\"\" class=\"wp-image-19626\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-300x200.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-1024x683.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-768x512.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-1536x1024.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-2048x1365.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-375x250.jpg 375w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-376x250.jpg 376w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-474x316.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-75x50.jpg 75w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-900x600.jpg 900w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-1700x1133.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-1352x901.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-800x533.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-180x120.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-153x102.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/01\/jbernth-230x153.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/figure>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-julie-bernth\">julie bernth<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Afdelingschef <br>Broer og konstruktioner<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-e59d63ec62513062d14ad51fa14ab51e\"><a href=\"mailto:JBERNTH@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">JBERNTH@systra.com<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-scaled.jpg\" alt=\"\" class=\"wp-image-1973\" style=\"width:186px;height:auto\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-300x225.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-1024x768.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-768x576.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-1536x1152.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-2048x1536.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-474x355.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-1700x1275.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-1352x1014.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-800x600.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-180x135.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-153x115.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/wang1733-1-230x172.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-dorte-wang\">Dorte Wang<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Afdelingschef<br>Risk Management<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-39120bd9cc2f8bd1152f0cca4adee489\"><a href=\"mailto:DWANG1@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">DWANG1@systra.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-scaled.jpg\" alt=\"\" class=\"wp-image-1978\" style=\"width:186px\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-300x225.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-1024x768.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-768x576.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-1536x1152.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-2048x1536.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-474x356.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-1700x1275.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-1352x1014.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-800x600.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-180x135.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-153x115.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/hoel1434-1-230x173.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-lars-holledig\">Lars H\u00f8lledig<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Kvalitetschef<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-cd1a80551645e65c5ddffef7a602c35c\"><a href=\"mailto:LHOELLEDIG@systra.com\">LHOELLEDIG@systra.com<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-scaled.jpg\" alt=\"\" class=\"wp-image-1977\" style=\"width:183px;height:auto\" srcset=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-scaled.jpg 2560w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-300x225.jpg 300w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-1024x768.jpg 1024w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-768x576.jpg 768w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-1536x1152.jpg 1536w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-2048x1536.jpg 2048w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-474x356.jpg 474w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-1700x1275.jpg 1700w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-1352x1014.jpg 1352w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-800x600.jpg 800w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-180x135.jpg 180w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-153x115.jpg 153w, https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2024\/01\/virk3806-2-230x173.jpg 230w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-maria-virklund\">Maria Virklund<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Afdelingschef <br>Business development<\/p>\n\n\n\n<p class=\"has-dusty-blue-color has-text-color has-link-color wp-elements-0e6b47638917940cdbc337aeda0f7814\"><a href=\"mailto:MVIRKLUND@systra.com\" target=\"_blank\" rel=\"noreferrer noopener\">MVIRKLUND@systra.com<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>DIREKTION Eva rindom Administrerende direkt\u00f8r ERINDOM@systra.com Kristian Quarder Finansdirekt\u00f8r KQUARDER@systra.com Annelise zidi HR-direkt\u00f8r AZIDI@systra.com Eli SKop Direkt\u00f8r, Consultancy ESKOP@systra.com Claus Madvig Petersen Direkt\u00f8r, Civils CPETERSEN@systra.com Thomas Vesterholm Direkt\u00f8r, Rail TVESTERHOLM@systra.com AFDELINGSLEDELSE Julie Feddersen GruppelederSpor og anl\u00e6g JJFEDDERSEN@systra.com Johan Hartnack AfdelingschefGIS &amp; digital JHARTNACK@systra.com Rune Mikkelsen Afdelingschef Systems RMIKKELSEN@systra.com Martin Vilhelmsen AfdelingschefMilj\u00f8, vand og areal MVILHELMSEN@systra.com [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":37310,"parent":363,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"903,468,820,733,886,637","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-1356","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ledelse i Danmark - SYSTRA Danmark<\/title>\n<meta name=\"description\" content=\"Ledelse i Danmark - SYSTRA er en af verdens f\u00f8rende ingeni\u00f8r- og r\u00e5dgivningskoncerner med speciale i offentlig transport og mobilitetsl\u00f8sninger.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ledelse i Danmark\" \/>\n<meta property=\"og:description\" content=\"Ledelse i Danmark - SYSTRA er en af verdens f\u00f8rende ingeni\u00f8r- og r\u00e5dgivningskoncerner med speciale i offentlig transport og mobilitetsl\u00f8sninger.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.systra.com\/denmark\/hvem-vi-er\/ledelse-i-danmark\/\" \/>\n<meta property=\"og:site_name\" content=\"Denmark\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T09:34:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/05\/fl_station-bus-cykler-metro-72-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/hvem-vi-er\\\/ledelse-i-danmark\\\/\",\"url\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/hvem-vi-er\\\/ledelse-i-danmark\\\/\",\"name\":\"Ledelse i Danmark - SYSTRA Danmark\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/hvem-vi-er\\\/ledelse-i-danmark\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/hvem-vi-er\\\/ledelse-i-danmark\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2025\\\/05\\\/fl_station-bus-cykler-metro-72-scaled.jpg\",\"datePublished\":\"2024-01-20T13:32:24+00:00\",\"dateModified\":\"2026-02-27T09:34:15+00:00\",\"description\":\"Ledelse i Danmark - SYSTRA er en af verdens f\u00f8rende ingeni\u00f8r- og r\u00e5dgivningskoncerner med speciale i offentlig transport og mobilitetsl\u00f8sninger.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/hvem-vi-er\\\/ledelse-i-danmark\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.systra.com\\\/denmark\\\/hvem-vi-er\\\/ledelse-i-danmark\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/hvem-vi-er\\\/ledelse-i-danmark\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2025\\\/05\\\/fl_station-bus-cykler-metro-72-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2025\\\/05\\\/fl_station-bus-cykler-metro-72-scaled.jpg\",\"width\":2560,\"height\":1714},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/hvem-vi-er\\\/ledelse-i-danmark\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hvem vi er\",\"item\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/hvem-vi-er\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ledelse i Danmark\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/#website\",\"url\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/\",\"name\":\"Denmark\",\"description\":\"Un site utilisant Les sites de Systra\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.systra.com\\\/denmark\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ledelse i Danmark - SYSTRA Danmark","description":"Ledelse i Danmark - SYSTRA er en af verdens f\u00f8rende ingeni\u00f8r- og r\u00e5dgivningskoncerner med speciale i offentlig transport og mobilitetsl\u00f8sninger.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Ledelse i Danmark","og_description":"Ledelse i Danmark - SYSTRA er en af verdens f\u00f8rende ingeni\u00f8r- og r\u00e5dgivningskoncerner med speciale i offentlig transport og mobilitetsl\u00f8sninger.","og_url":"https:\/\/www.systra.com\/denmark\/hvem-vi-er\/ledelse-i-danmark\/","og_site_name":"Denmark","article_modified_time":"2026-02-27T09:34:15+00:00","og_image":[{"width":2560,"height":1714,"url":"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/05\/fl_station-bus-cykler-metro-72-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.systra.com\/denmark\/hvem-vi-er\/ledelse-i-danmark\/","url":"https:\/\/www.systra.com\/denmark\/hvem-vi-er\/ledelse-i-danmark\/","name":"Ledelse i Danmark - SYSTRA Danmark","isPartOf":{"@id":"https:\/\/www.systra.com\/denmark\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.systra.com\/denmark\/hvem-vi-er\/ledelse-i-danmark\/#primaryimage"},"image":{"@id":"https:\/\/www.systra.com\/denmark\/hvem-vi-er\/ledelse-i-danmark\/#primaryimage"},"thumbnailUrl":"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/05\/fl_station-bus-cykler-metro-72-scaled.jpg","datePublished":"2024-01-20T13:32:24+00:00","dateModified":"2026-02-27T09:34:15+00:00","description":"Ledelse i Danmark - SYSTRA er en af verdens f\u00f8rende ingeni\u00f8r- og r\u00e5dgivningskoncerner med speciale i offentlig transport og mobilitetsl\u00f8sninger.","breadcrumb":{"@id":"https:\/\/www.systra.com\/denmark\/hvem-vi-er\/ledelse-i-danmark\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.systra.com\/denmark\/hvem-vi-er\/ledelse-i-danmark\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.systra.com\/denmark\/hvem-vi-er\/ledelse-i-danmark\/#primaryimage","url":"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/05\/fl_station-bus-cykler-metro-72-scaled.jpg","contentUrl":"https:\/\/www.systra.com\/denmark\/wp-content\/uploads\/sites\/26\/2025\/05\/fl_station-bus-cykler-metro-72-scaled.jpg","width":2560,"height":1714},{"@type":"BreadcrumbList","@id":"https:\/\/www.systra.com\/denmark\/hvem-vi-er\/ledelse-i-danmark\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.systra.com\/denmark\/"},{"@type":"ListItem","position":2,"name":"Hvem vi er","item":"https:\/\/www.systra.com\/denmark\/hvem-vi-er\/"},{"@type":"ListItem","position":3,"name":"Ledelse i Danmark"}]},{"@type":"WebSite","@id":"https:\/\/www.systra.com\/denmark\/#website","url":"https:\/\/www.systra.com\/denmark\/","name":"Denmark","description":"Un site utilisant Les sites de Systra","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.systra.com\/denmark\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"lang":"da","translations":{"da":1356,"en":52923},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.systra.com\/denmark\/wp-json\/wp\/v2\/pages\/1356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.systra.com\/denmark\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.systra.com\/denmark\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.systra.com\/denmark\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/www.systra.com\/denmark\/wp-json\/wp\/v2\/comments?post=1356"}],"version-history":[{"count":3,"href":"https:\/\/www.systra.com\/denmark\/wp-json\/wp\/v2\/pages\/1356\/revisions"}],"predecessor-version":[{"id":67097,"href":"https:\/\/www.systra.com\/denmark\/wp-json\/wp\/v2\/pages\/1356\/revisions\/67097"}],"up":[{"embeddable":true,"href":"https:\/\/www.systra.com\/denmark\/wp-json\/wp\/v2\/pages\/363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.systra.com\/denmark\/wp-json\/wp\/v2\/media\/37310"}],"wp:attachment":[{"href":"https:\/\/www.systra.com\/denmark\/wp-json\/wp\/v2\/media?parent=1356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}